{"id":19522,"date":"2022-11-24T17:04:00","date_gmt":"2022-11-24T15:04:00","guid":{"rendered":"https:\/\/\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/"},"modified":"2024-09-13T17:28:47","modified_gmt":"2024-09-13T15:28:47","slug":"la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona","status":"publish","type":"post","link":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/","title":{"rendered":"La tecnol\u00f2gica MiWEndo instal\u00b7la la seva seu corporativa a Barcelona"},"content":{"rendered":"<p><em>La companyia ha escollit unes <strong>c&egrave;ntriques oficines<\/strong> a la capital catalana i ha comptat amb l&rsquo;assessorament de <strong>FORCADELL<\/strong>.&nbsp;&nbsp;<\/em><\/p>\n<div>\n<p>La spin off <a href=\"https:\/\/www.miwendo.com\/\" target=\"_blank\" rel=\"noopener\">MiWEndo<\/a>, dedicada a l&rsquo;&agrave;mbit de la innovaci&oacute; tecnol&ograve;gica, instal&middot;lar&agrave; properament la seva seu a Barcelona, a una <strong>zona molt prestigiosa i concorreguda de la ciutat<\/strong>, molt a prop de la pl. Francesc Maci&agrave; i de l&rsquo;av. Diagonal. Les oficines arrendades disposen de <strong>240 m&sup2; de superf&iacute;cie<\/strong>, <strong>amplis despatxos amb balc&oacute; i sales de reuni&oacute; polivalents<\/strong>. Les diferents estances disposen, a m&eacute;s a m&eacute;s, d&rsquo;<strong>&agrave;mplies entrades de llum natural <\/strong>contribuint al benestar dels empleats. Segons Ignasi Belda, CEO de MiWEndo, &ldquo;l&rsquo;oficina que hem escollit s&rsquo;ajusta molt a les nostres necessitats actuals, tant pel que fa a <em>superf&iacute;cie i distribuci&oacute; dels espais<\/em>, com a nivell d&rsquo;<strong>ubicaci&oacute; i altres caracter&iacute;stiques<\/strong>&rdquo;.&nbsp;&nbsp;<\/p>\n<\/p>\n<p>Segons Manel de Bes, director del <a href=\"https:\/\/www.forcadelloficina.com\/\" target=\"_blank\" rel=\"noopener\">Departament d&rsquo;Oficines de FORCADEL<\/a>L, &ldquo;les empreses de <strong>perfil tecnol&ograve;gic<\/strong> com MiWEndo, juntament amb les <strong><em>life science<\/em><\/strong> i les de l&rsquo;&agrave;mbit de la <strong>formaci&oacute;<\/strong> estan registrant aquest 2022 una <strong>gran activitat al mercat d&rsquo;oficines de Barcelona<\/strong>. Sens dubte, l&rsquo;atractiu de la ciutat &eacute;s un <strong>reclam molt valorat per les empreses i l&rsquo;atracci&oacute; de talent<\/strong>.&rdquo;<\/p>\n<p>Des de la seva creaci&oacute; durant la pand&egrave;mia i fins a dia d&rsquo;avui MiWEndo <strong>ha desenvolupat la seva activitat en remot<\/strong>, sense oficina f&iacute;sica, per la qual cosa el creixement assolit ha propiciat la <strong>necessitat de disposar d&rsquo;una seu f&iacute;sica<\/strong>. Actualment la companyia est&agrave; treballant en un <strong>dispositiu m&egrave;dic accessori per a endosc&ograve;pies per a reduir la incid&egrave;ncia i mortalitat del c&agrave;ncer colorectal.<\/strong>&nbsp;<\/p>\n<p>MiWEndo Solutions &eacute;s una <em>spin-off <\/em>de la Universitat Pompeu Fabra, Universitat Polit&egrave;cnica de Catalunya, Hospital Cl&iacute;nic de Barcelona i la Instituci&oacute; Catalana de Recerca i Estudis Avan&ccedil;ats que treballa en el desenvolupament de <strong>solucions tecnol&ograve;giques aplicades al diagn&ograve;stic de malalties amb processos tumorals<\/strong>. La companyia ha rebut <strong>nombrosos reconeixements<\/strong> per la seva tasca, com per exemple, el I Premi Innovaci&oacute; Campus Cl&iacute;nic, DWF-RCD Award, Premi Josemi Azkoitia, Healthy Longevity Global Grand Challenge Award, Premi Dona TIC, Premi Societat Catalana de Biologia Startup, The Spinoff Prize, a Nature Research Award, Fundaci&oacute;n MAPFRE Social, Innovation Awards, Brightlands Award i el Premi Consell Social UPF.&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La companyia ha escollit unes c&egrave;ntriques oficines a la capital catalana i ha comptat amb l&rsquo;assessorament de FORCADELL.&nbsp;&nbsp; La spin off MiWEndo, dedicada a l&rsquo;&agrave;mbit de la innovaci&oacute; tecnol&ograve;gica, instal&middot;lar&agrave; properament la seva seu a Barcelona, a una zona molt prestigiosa i concorreguda de la ciutat, molt a prop de la pl. Francesc Maci&agrave; i [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":19889,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[77,71],"tags":[],"class_list":["post-19522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporatiu","category-corporativo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La tecnol\u00f2gica MiWEndo instal\u00b7la la seva seu corporativa a Barcelona - Forcadell<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La tecnol\u00f2gica MiWEndo instal\u00b7la la seva seu corporativa a Barcelona - Forcadell\" \/>\n<meta property=\"og:description\" content=\"La companyia ha escollit unes c&egrave;ntriques oficines a la capital catalana i ha comptat amb l&rsquo;assessorament de FORCADELL.&nbsp;&nbsp; La spin off MiWEndo, dedicada a l&rsquo;&agrave;mbit de la innovaci&oacute; tecnol&ograve;gica, instal&middot;lar&agrave; properament la seva seu a Barcelona, a una zona molt prestigiosa i concorreguda de la ciutat, molt a prop de la pl. Francesc Maci&agrave; i [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Forcadell\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-24T15:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-13T15:28:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/20221124012230-microsoftteams-image-70-1360x636.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1360\" \/>\n\t<meta property=\"og:image:height\" content=\"636\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuts\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La tecnol\u00f2gica MiWEndo instal\u00b7la la seva seu corporativa a Barcelona - Forcadell","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/","og_locale":"ca_ES","og_type":"article","og_title":"La tecnol\u00f2gica MiWEndo instal\u00b7la la seva seu corporativa a Barcelona - Forcadell","og_description":"La companyia ha escollit unes c&egrave;ntriques oficines a la capital catalana i ha comptat amb l&rsquo;assessorament de FORCADELL.&nbsp;&nbsp; La spin off MiWEndo, dedicada a l&rsquo;&agrave;mbit de la innovaci&oacute; tecnol&ograve;gica, instal&middot;lar&agrave; properament la seva seu a Barcelona, a una zona molt prestigiosa i concorreguda de la ciutat, molt a prop de la pl. Francesc Maci&agrave; i [&hellip;]","og_url":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/","og_site_name":"Forcadell","article_published_time":"2022-11-24T15:04:00+00:00","article_modified_time":"2024-09-13T15:28:47+00:00","og_image":[{"width":1360,"height":636,"url":"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/20221124012230-microsoftteams-image-70-1360x636.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/#article","isPartOf":{"@id":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/"},"author":{"name":"","@id":""},"headline":"La tecnol\u00f2gica MiWEndo instal\u00b7la la seva seu corporativa a Barcelona","datePublished":"2022-11-24T15:04:00+00:00","dateModified":"2024-09-13T15:28:47+00:00","mainEntityOfPage":{"@id":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/"},"wordCount":465,"image":{"@id":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/20221124012230-microsoftteams-image-70.png","articleSection":["Corporatiu","Corporativo"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/","url":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/","name":"La tecnol\u00f2gica MiWEndo instal\u00b7la la seva seu corporativa a Barcelona - Forcadell","isPartOf":{"@id":"https:\/\/forcadell.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/20221124012230-microsoftteams-image-70.png","datePublished":"2022-11-24T15:04:00+00:00","dateModified":"2024-09-13T15:28:47+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/#primaryimage","url":"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/20221124012230-microsoftteams-image-70.png","contentUrl":"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/20221124012230-microsoftteams-image-70.png","width":2667,"height":1751},{"@type":"BreadcrumbList","@id":"https:\/\/forcadell.com\/ca\/la-tecnologica-miwendo-installa-la-seva-seu-corporativa-a-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/forcadell.com\/ca\/"},{"@type":"ListItem","position":2,"name":"La tecnol\u00f2gica MiWEndo instal\u00b7la la seva seu corporativa a Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/forcadell.com\/ca\/#website","url":"https:\/\/forcadell.com\/ca\/","name":"Forcadell","description":"Inmobiliaria Barcelona | Consultores inmobiliarios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forcadell.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts\/19522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/comments?post=19522"}],"version-history":[{"count":1,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts\/19522\/revisions"}],"predecessor-version":[{"id":19892,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts\/19522\/revisions\/19892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/media\/19889"}],"wp:attachment":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/media?parent=19522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/categories?post=19522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/tags?post=19522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}