{"id":19518,"date":"2022-09-15T17:04:00","date_gmt":"2022-09-15T15:04:00","guid":{"rendered":"https:\/\/\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/"},"modified":"2024-09-13T17:30:13","modified_gmt":"2024-09-13T15:30:13","slug":"la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona","status":"publish","type":"post","link":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/","title":{"rendered":"La cadena catalana 365 Obrador obre un nou establiment a Barcelona"},"content":{"rendered":"<p><em><strong>FORCADELL ha assessorat a 365 Obrador <\/strong>en l&rsquo;obertura d&rsquo;un nou local al carrer Selva de Mar 125, al Poblenou.<\/em><\/p>\n<p><em><img decoding=\"async\" alt=\"\" src=\"https:\/wp-content\/uploads\/2024\/09\/20220915104804-portada-obrador-365-896x636.png\" \/><\/em><\/p>\n<p>La cadena de forns i cafeteries <a href=\"https:\/\/365obrador.com\/\" target=\"_blank\" rel=\"noopener\"><strong>365 Obrador<\/strong><\/a> <strong>s&rsquo;expandeix a Barcelona amb l&rsquo;obertura d&rsquo;un nou obrador al carrer Selva de Mar 125<\/strong>, al barri del <strong>Poblenou<\/strong>. El <a href=\"https:\/\/www.forcadelllocalcomercial.com\/\" target=\"_blank\" rel=\"noopener\">departament de Locals Comercials de FORCADELL<\/a> ha assessorat a l&rsquo;empresa en l&rsquo;arrendament del nou <strong>local comercial<\/strong> de 135 m&sup2; de superf&iacute;cie, <strong>situat a la planta baixa d&rsquo;un complex d&rsquo;edificis exclusius d&rsquo;oficines.<\/strong><\/p>\n<p><strong>365 Obrador<\/strong> ha escollit aquestes noves instal&middot;lacions ubicades al <strong>22@ <\/strong>pel creixement que est&agrave; experimentant el districte. La <strong>cadena&nbsp;<\/strong>de forns i cafeteries <strong>busca oferir els seus serveis als ve&iuml;ns del barri<\/strong>, treballadors dels nous edificis corporatius, universitats i centres de recerca de la zona, entre d&rsquo;altres. Actualment el local est&agrave; en proc&eacute;s de reforma i <strong>es preveu inaugurar-lo a finals d&rsquo;octubre<\/strong>.<\/p>\n<p>Segons <strong>Ana Fuertes<\/strong>, Directora del Departament de Locals Comercials de <a href=\"https:\/\/www.forcadell.com\/\" target=\"_blank\" rel=\"noopener\"><strong>FORCADELL<\/strong><\/a>, &ldquo;els locals comercials amb superf&iacute;cies com la del nou establiment de 365 Obrador &ndash;d&rsquo;entre 80 fins a 200 m&sup2; &#8211; acumulen un <strong>47% de la demanda de mercat<\/strong>, tal com es recull a l&rsquo;<a href=\"https:\/\/www.forcadell.com\/es\/publicacions.html\" target=\"_blank\" rel=\"noopener\">Informe de Mercat de <em>Retail<\/em> publicat a l&rsquo;1S 2022<\/a>&rdquo;. &ldquo;<strong>Aquesta demanda es mant&eacute; de manera estable<\/strong> any rere any com la m&eacute;s sol&middot;licitada&rdquo;, conclou <strong>Fuertes<\/strong>. Per altra banda, <strong>Xavier Fuertes<\/strong>, Responsable d&rsquo;Expansi&oacute; de 365 Obrador afirma que &ldquo;<strong>aquesta nova obertura<\/strong>, a m&eacute;s de proporcionar activitat al Poblenou, <strong>consolida el creixement de la nostra cadena a la ciutat de Barcelona<\/strong>, ja que amb aquesta sumen un total de 112 a la ciutat&rdquo;.<\/p>\n<p>El districte del 22@, i concretament on es situar&agrave; el nou establiment, compta amb unes <strong>bones comunicacions amb transport p&uacute;blic<\/strong>. Es troba molt ben connectat amb diverses l&iacute;nies de bus, metro i tramvia a escassos minuts a peu. El nou local es troba a molt poca dist&agrave;ncia de l&rsquo;<strong>Avinguda Diagonal<\/strong>, una de les principals vies de la ciutat.<\/p>\n<p><strong>365 Obrador<\/strong> &eacute;s una empresa familiar <strong>fundada fa m&eacute;s de 21 anys<\/strong> i implantada a la prov&iacute;ncia de Barcelona. Compta amb <strong>700 treballadors repartits entre les 160 botigues<\/strong> <strong>pr&ograve;pies i franquiciades<\/strong>. Disposa de <strong>dos models de negoci<\/strong>: d&rsquo;una banda, botigues de pa amb cafeteria que es proveeixen des de l&rsquo;obrador central de <strong>L&rsquo;Hospitalet de Llobregat<\/strong> i de l&rsquo;altra, establiments amb obrador propi des d&rsquo;on s&rsquo;elaboren els productes a diari. Els dos models tenen en com&uacute; l&rsquo;<strong>obertura dels establiments els 365 dies a l&rsquo;any<\/strong>, amb excepcions d&rsquo;horaris depenent del dia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FORCADELL ha assessorat a 365 Obrador en l&rsquo;obertura d&rsquo;un nou local al carrer Selva de Mar 125, al Poblenou. La cadena de forns i cafeteries 365 Obrador s&rsquo;expandeix a Barcelona amb l&rsquo;obertura d&rsquo;un nou obrador al carrer Selva de Mar 125, al barri del Poblenou. El departament de Locals Comercials de FORCADELL ha assessorat a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":17427,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[77,71],"tags":[],"class_list":["post-19518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporatiu","category-corporativo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La cadena catalana 365 Obrador obre un nou establiment a Barcelona - Forcadell<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La cadena catalana 365 Obrador obre un nou establiment a Barcelona - Forcadell\" \/>\n<meta property=\"og:description\" content=\"FORCADELL ha assessorat a 365 Obrador en l&rsquo;obertura d&rsquo;un nou local al carrer Selva de Mar 125, al Poblenou. La cadena de forns i cafeteries 365 Obrador s&rsquo;expandeix a Barcelona amb l&rsquo;obertura d&rsquo;un nou obrador al carrer Selva de Mar 125, al barri del Poblenou. El departament de Locals Comercials de FORCADELL ha assessorat a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Forcadell\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-15T15:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-13T15:30:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/3179_FORCADELL____365-OBRADOR-1360x636.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1360\" \/>\n\t<meta property=\"og:image:height\" content=\"636\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuts\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La cadena catalana 365 Obrador obre un nou establiment a Barcelona - Forcadell","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/","og_locale":"ca_ES","og_type":"article","og_title":"La cadena catalana 365 Obrador obre un nou establiment a Barcelona - Forcadell","og_description":"FORCADELL ha assessorat a 365 Obrador en l&rsquo;obertura d&rsquo;un nou local al carrer Selva de Mar 125, al Poblenou. La cadena de forns i cafeteries 365 Obrador s&rsquo;expandeix a Barcelona amb l&rsquo;obertura d&rsquo;un nou obrador al carrer Selva de Mar 125, al barri del Poblenou. El departament de Locals Comercials de FORCADELL ha assessorat a [&hellip;]","og_url":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/","og_site_name":"Forcadell","article_published_time":"2022-09-15T15:04:00+00:00","article_modified_time":"2024-09-13T15:30:13+00:00","og_image":[{"width":1360,"height":636,"url":"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/3179_FORCADELL____365-OBRADOR-1360x636.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/#article","isPartOf":{"@id":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/"},"author":{"name":"","@id":""},"headline":"La cadena catalana 365 Obrador obre un nou establiment a Barcelona","datePublished":"2022-09-15T15:04:00+00:00","dateModified":"2024-09-13T15:30:13+00:00","mainEntityOfPage":{"@id":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/"},"wordCount":489,"image":{"@id":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/3179_FORCADELL____365-OBRADOR.png","articleSection":["Corporatiu","Corporativo"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/","url":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/","name":"La cadena catalana 365 Obrador obre un nou establiment a Barcelona - Forcadell","isPartOf":{"@id":"https:\/\/forcadell.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/3179_FORCADELL____365-OBRADOR.png","datePublished":"2022-09-15T15:04:00+00:00","dateModified":"2024-09-13T15:30:13+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/#primaryimage","url":"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/3179_FORCADELL____365-OBRADOR.png","contentUrl":"https:\/\/forcadell.com\/wp-content\/uploads\/2024\/09\/3179_FORCADELL____365-OBRADOR.png","width":2667,"height":1751},{"@type":"BreadcrumbList","@id":"https:\/\/forcadell.com\/ca\/la-cadena-catalana-365-obrador-obre-un-nou-establiment-a-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/forcadell.com\/ca\/"},{"@type":"ListItem","position":2,"name":"La cadena catalana 365 Obrador obre un nou establiment a Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/forcadell.com\/ca\/#website","url":"https:\/\/forcadell.com\/ca\/","name":"Forcadell","description":"Inmobiliaria Barcelona | Consultores inmobiliarios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forcadell.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts\/19518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/comments?post=19518"}],"version-history":[{"count":1,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts\/19518\/revisions"}],"predecessor-version":[{"id":19905,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts\/19518\/revisions\/19905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/media\/17427"}],"wp:attachment":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/media?parent=19518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/categories?post=19518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/tags?post=19518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}