{"id":19499,"date":"2020-10-26T17:03:00","date_gmt":"2020-10-26T15:03:00","guid":{"rendered":"https:\/\/\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/"},"modified":"2024-10-02T17:12:11","modified_gmt":"2024-10-02T15:12:11","slug":"forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020","status":"publish","type":"post","link":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/","title":{"rendered":"FORCADELL i la UB han presentat l\u2019INFORME ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI 2020"},"content":{"rendered":"<p>FORCADELL ha presentat en format webinar l&rsquo;edici&oacute; 2020 de l&rsquo;informe ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI elaborat conjuntament amb la Universitat de Barcelona. La pon&egrave;ncia principal ha estat a c&agrave;rrec del Director Editorial de l&rsquo;Informe FORCADELL-UB, el dr. Gonzalo Bernardos, professor titular d&rsquo;Economia de la UB i Director del M&agrave;ster d&rsquo;Assessoria, Gesti&oacute; i Promoci&oacute; Immobili&agrave;ria de la UB.&nbsp; L&rsquo;han acompanyat a la taula de debat el sr. Ivan Vaqu&eacute;, CEO de FORCADELL, Antonio L&oacute;pez, Director de l&rsquo;&Agrave;rea d&rsquo;Immobili&agrave;ria d&rsquo;Empresa de FORCADELL, Marta Vilana, Directora de l&rsquo;&Agrave;rea Residencial de FORCADELL i Llu&iacute;s Catal&agrave;, advocat i Director de l&rsquo;&Agrave;rea Gesti&oacute; &ndash; Corporativa de FORCADELL. La trobada digital ha repassat l&rsquo;actualitat del sector immobiliari (Residencial i Terciari) i les seves perspectives en un context condicionat per la Covid-19 i una situaci&oacute; econ&ograve;mica de molta incertesa.<\/p>\n<p style=\"text-align: justify;margin-left: 280px\"><a href=\"https:\/\/youtu.be\/jPjyAB6cDWc\"><\/a><\/p>\n<p><strong>Torn&nbsp;de preguntes del webinar FORCADELL &ndash; UB 2019&nbsp;<\/strong><\/p>\n<p><strong>&iquest;C&oacute;mo est&aacute; cambiando la demanda de compra? &iquest;Cu&aacute;nto se prev&eacute; que bajen los precios del sector inmobiliario?<\/strong><\/p>\n<p>(M. Vilana) Estamos viviendo una disminuci&oacute;n de la demanda debido a la inestabilidad laboral actual y al retraso en las decisiones de compra. Es evidente que todos esperamos que los precios de compra bajen algo m&aacute;s, de aqu&iacute; esta demora en el proceso de decisi&oacute;n. Adem&aacute;s esta demanda se est&aacute; comportando de forma muy asim&eacute;trica.&nbsp;Comparativamente con los datos pre-Covid, estamos recibiendo muncha menos demanda en los n&uacute;cleos urbanos que en la periferia, y eso lo cambia todo. En estos momentos muchos propietarios cuentan con la intermediaci&oacute;n de una agencia inmobiliaria para ayudarles a vender su propiedad. Estamos teniendo un sobre-stock de oferta de producto, tal como se est&aacute; viendo en los portales. Esto est&aacute; cambiando las reglas del juego en el sector puesto que est&aacute;bamos acostumbrados a que fuese el propietario quien tuviese el poder de negociaci&oacute;n y ahora no es as&iacute;: el poder lo tiene ahora el comprador. Aunque no se aprecia de forma muy evidente en el sector, s&iacute; que se ve la diferencia de precio entre el asking price y el precio de cierre. En &eacute;poca pre-Covid pod&iacute;amos estar hablando de un diferencial de entre el 5% y el 10% y ahora, en entornos urbanos sobre todo, en torno al 15%. Ahora mismo es un momento excelente para comprar y lo seguir&aacute; siendo mientras dure la pandemia. Una vez se reactive la econom&iacute;a esta oportunidad se habr&aacute; terminado.&nbsp;&nbsp;<\/p>\n<p><strong>&iquest;Qu&eacute; opina del &Iacute;ndice de Precios de Alquiler marcado por la Generalitat de&nbsp; Catalunya y de las medidas que se han activado para controlar las subidas del alquiler?<\/strong><\/p>\n<p>(G. Bernardos) Hist&oacute;ricamente y bas&aacute;ndonos en teor&iacute;a econ&oacute;mica y en evidencias hist&oacute;ricas, establecer precios m&aacute;ximos en el mercado de alquiler ha sido siempre un desastre. Aqu&iacute; se intenta aplicar buscando una soluci&oacute;n populista. El Sindicat de Llogaters pretende que el inquilino siga vivienda donde vive y estableciendo el precio que quiere. Se intuye que esta medida pueda acabar aplic&aacute;ndose a nivel Estatal. El propietario pasar&aacute; a poner en su inmueble en alquiler en otra modalidad, como por ejemplo, como vivienda de temporada. Algunos las vender&aacute;n y otros las mantendr&aacute;n vac&iacute;as.&nbsp;<\/p>\n<p>Pocas viviendas en alquiler tienen aire acondicionado y calefacci&oacute;n central muchas menos. Nadie va a hacer ninguna reforma. Cuando pase la crisis, muchas personas querr&aacute;n alquilar en Barcelona y el propietario podr&aacute; elegir entre unos y otros y le podr&aacute; a&ntilde;adir el IBI,&nbsp; los gastos de Comunidad, e incluso podr&aacute;n pedir una cuota de entrada superior a la del propio alquiler (a parte del mismo), de por ejemplo de 4.000&euro; o 6.000&euro;. Administradores y agencias de alquiler realizar&aacute;n 2 funciones: una, llevar a cabo el alquiler en &lsquo;blanco&rsquo;, y otra, en &lsquo;negro&rsquo; si lo piden los propietarios. Cuando la oferta se reduce, el precio sube. El precio en el mercado &lsquo;blanco&rsquo; se queda igual y en el mercado &lsquo;negro&rsquo; se dispara, tal como dicen los libros de teor&iacute;a econ&oacute;mica. En conclusi&oacute;n, m&aacute;s problemas para todos, especialmente para aquellos a quienes deber&iacute;a beneficiarles, es decir la gente m&aacute;s humilde.&nbsp;<\/p>\n<p><strong>En caso de no haber referencias de precios de algunos tipos de pisos en una zona, &iquest;qu&eacute; deben hacer los propietarios?<\/strong><\/p>\n<p>(L. Catal&agrave;) La interpretaci&oacute;n del texto legal nos dice que debemos analizar 2 cosas: por un lado, si ha habido un contrato de arrendamiento en los &uacute;ltimos 5 a&ntilde;os deberemos ir como m&aacute;ximo a la renta pactada inicialmente y sino, deberemos ir al &Iacute;ndice. Si no existe ni el uno ni el otro no existe tope y por lo tanto la renta es libre. Es importante destacar tambi&eacute;n que el &Iacute;ndice no distingue entre el propietario que hace una inversi&oacute;n y lo rehabilita del que no hace nada. El &Iacute;ndice ser&aacute; el mismo y esto nos va a llevar a una degradaci&oacute;n del mercado de alquiler. El propietario que hasta ahora, cuando se produc&iacute;a una renuncia en el contrato de alquiler lo rehabilitaba y lo reordenaba para poder obtener una mayor rentabilidad dejar&aacute; de hacerlo puesto que el &Iacute;ndice ser&aacute; el mismo. Esto es todo lo contrario de lo que indica el pre&aacute;mbulo de la ley, del mismo modo que ocurre con todas las leyes relacionadas con el &aacute;mbito de la vivienda.<\/p>\n<p><strong>&iquest;Qu&eacute; soluci&oacute;n tienen los promotores para recuperar los ingresos del 30% de reserva de superficie para vivienda social?<\/strong><\/p>\n<p>(G. Bernardos) Pagar bastante menos por el suelo es la &uacute;nica posibilidad. A todos aquellos que ya hab&iacute;an comprado suelo, les han &lsquo;cogido&rsquo;. Es lastimoso que esto suceda poniendo trabas a la realizaci&oacute;n de vivienda nueva en determinadas ciudades de Catalunya. Esto es contraproducente puesto que volvemos a tener menos oferta, la demanda no depender&aacute; de las circunstancias econ&oacute;micas cuando vayan mejor, lo que va a generar una subida espectacular de las viviendas libres. En esta situaci&oacute;n no hay nadie que salga beneficiado. Estamos en una &eacute;poca llena de populismos y, desgraciadamente, esto es lo que nos est&aacute; tocando vivir.&nbsp;<\/p>\n<p><strong>&iquest;Se compensar&aacute; la reducci&oacute;n de superficie por teletrabajo con el aumento de superficie por puesto de trabajo para mejorar las condiciones de bienestar,&nbsp; contrariamente a lo sucedido en los &uacute;ltimos a&ntilde;os? &iquest;Recomienda que el coworking est&eacute; enfocado para usuarios del mismo sector, donde encuentren sinergias, o para cualquiera que desee un espacio para ejercer su trabajo, sin importar la actividad?<\/strong><\/p>\n<p>(G. Bernardos) La mampara, como medida preventiva, se vuelve milagrosa y evita cualquier contagio. En este caso dudo much&iacute;simo que aumente la superficie por persona en un coworking. La clave del negocio del coworking es muy sencilla: el precio del m2 es superior al de oficina y la empresa correspondiente utiliza menos m2, bien porque est&aacute; mejor delimitado el espacio o porque realmente hay mucho trabajador con flexibilidad. El gran &eacute;xito del coworking es que su gestor obtiene m&aacute;s rentas que con la oficina pero el que paga, paga menos. Yo creo mucho en los coworkings tem&aacute;ticos. Por ejemplo, un coworking m&eacute;dico o legal. En el caso de un coworking m&eacute;dico recomendar&iacute;a subrogas las actividades administrativas.<\/p>\n<p>(T. L&oacute;pez) En el primer trimestre del a&ntilde;o el sector del coworking empez&oacute; con mucha fuerza y con unos resultados muy buenos. La densidad actual de los coworkings es de 1 persona por cada 10 m2 mientras que en los edificios que tienen unas evacuaciones mejores y espec&iacute;ficas pueden llegar a una densidad de 1 persona por cada 5 m2. Es verdad que no hay una normativa vigente que especifique esa situaci&oacute;n. Lo que s&iacute; que hemos notado es que en este periodo de pandemia, m&aacute;s o menos el 85% de las empresas que estaban buscando una alternativa de cambio y buscando oficinas, todas ellas est&aacute;n mirando una disminuci&oacute;n del espacio de entre un 30% y un 50%. Es un dato importante puesto que ahora hay una gran apuesta por la flexibilidad y el teletrabajo.<\/p>\n<p><strong>En el Baix Pened&egrave;s a&uacute;n no se ha detectado ninguna bajada significante de precios del suelo o naves industriales &iquest;La administraci&oacute;n podr&iacute;a participar en esta esperada bajada subastando las parcelas municipales?<\/strong><\/p>\n<p>(G. Bernardos) Lo que haga la Administraci&oacute;n en estos momentos me parece una caja de sorpresas. Si la Administraci&oacute;n saca m&aacute;s suelo para su venta podr&aacute; ayudar a que el precio pueda bajar. No obstante, dada la voracidad que hay de compra de suelo en naves industriales la bajada ser&aacute; m&iacute;nima. En el momento en que el momento sea mayor para naves log&iacute;sticas y en menor medida para las naves industriales, el problema ser&aacute; encontrar una oferta que cumpla la reglamentaci&oacute;n que la Administraci&oacute;n p&uacute;blica establece.&nbsp;<\/p>\n<p>(T. L&oacute;pez) El Pened&egrave;s es una zona que tiene ciertas complicaciones puesto que tradicionalmente vive del vino y del cava y necesita esas tierras para el cultivo de la uva. Hay plataformas vitivin&iacute;colas que est&aacute;n protegiendo el territorio y delimitando la expansi&oacute;n de centros log&iacute;sticos. La proximidad del Pened&egrave;s con la autopista hace que resulte muy atractivo para el sector log&iacute;stico. Muchas veces sucede que las instituciones tienen intereses contrapuestos con la inversi&oacute;n privada y prefieren desarrollar y sacar al mercado sus parques antes que desarrollarlos por iniciativa privada.&nbsp;<\/p>\n<p><strong>&iquest;C&oacute;mo podemos promover el coliving con el vac&iacute;o jur&iacute;dico de esta f&oacute;rmula y la animadversi&oacute;n del Ajuntament de Barcelona que la persigue confundi&eacute;ndola con el alquiler tur&iacute;stico?&nbsp;<\/strong><\/p>\n<p>(T. L&oacute;pez) La ausencia de legislaci&oacute;n es un problema y la sobre-legislaci&oacute;n es otro. Es verdad que todo lo que est&aacute; relacionado con el coliving no est&aacute; bien legislado. La operativa al final es contrato LAU de arrendamientos de un mes y un d&iacute;a. Hay que tener en cuenta que el coliving es un formato en el que el periodo medio de ocupaci&oacute;n es de 6 meses. Las personas tienen una tendencia al cambio, bien para buscar otros colivings o bien porque tienen una movilidad geogr&aacute;fica determinada. Al final buscan &lsquo;comunidad&rsquo;. Todo el mundo que quiera tener el futuro en el inmobiliario tiene que pivotar en 3 aspectos que son los que veremos en el futuro: la vivienda\/familia, trabajo y ocio. Cada vez m&aacute;s estamos viendo que los desarrollos van en esa l&iacute;nea.&nbsp;<br \/>\nHay un modelo de coliving en edificio completo de proyecto nuevo y otro que sigue un modelo de alquiler habitacional. Aunque se definan estos conceptos con anglicismos no deja de ser una evoluci&oacute;n del alquiler de habitaciones. Lo mismo sucede con el build to rent, que en realidad ha existido siempre y que consiste en que un promotor destina un edificio al alquiler. Simplemente es el mismo concepto pero pivotado en el concepto de &lsquo;comunidad&rsquo;.&nbsp;<\/p>\n<p><strong>&iquest;Est&aacute;is mirando construcci&oacute;n de edificios\/proyectos con nuevos modelos de negocio tipo airbnb, Welive? &iquest;C&oacute;mo veis el desarrollo de este tipo de proyectos?&nbsp;<\/strong><\/p>\n<p>(Ivan Vaqu&eacute;) Todos estos conceptos &lsquo;co&rsquo; son modelos parecidos al sharing economy. Ya hemos visto modelos como AirBnb o Cabify, los cuales son modelos nuevos que no ten&iacute;an regulaci&oacute;n puesto que esta no exist&iacute;a. La tecnolog&iacute;a ha hecho desplazar modelos antiguos, es decir, que no cambian el servicio sino que lo ofrecen de otra forma, por ejemplo, ofreciendo un servicio m&aacute;s r&aacute;pido, m&aacute;s econ&oacute;mico y de mejor adaptaci&oacute;n. Todos estos modelos se basan en una entrada muy r&aacute;pida en el mercado, tanto que cuando la legislaci&oacute;n o los lobbys anteriores se dan cuenta estos ya han crecido tanto que no se pueden delimitar de forma f&aacute;cil y hay que negociar, tal como sucedi&oacute; con Cabify y los taxistas. Es lo que ha hecho AirBnb tambi&eacute;n en muchas ciudades. Cuando su implantaci&oacute;n en muchas ciudades ya era muy extensa y el sistema implantado anteriormente ha querido pararlo ha sido muy complicado, precisamente por su elevado n&uacute;mero de usuarios y adeptos. La Covid-19 lo ha frenado en seco como, por ejemplo, grandes proyectos de colivings evolucionados en Barcelona y que han quedado parados. La Administraci&oacute;n puede aprovechar para implantar una nueva legislaci&oacute;n que lo bloquee m&aacute;s pero estamos convencidos de que todo lo que aporte una mejora siempre acabar&aacute; imponi&eacute;ndose. En este sentido la legislaci&oacute;n lo va a poder frenar pero en ning&uacute;n caso parar. De hecho, si tenemos las herramientas a punto cuando esta pandemia termine estos modelos van a seguir avanzando m&aacute;s deprisa que el modelo tradicional y acabar&aacute;n implant&aacute;ndose. No est&aacute;n parados, est&aacute;n estudiando nuevas manera de evolucionar. Seguramente el coliving que veremos en 2025 o 2030 no tendr&aacute; nada que ver con el coliving como lo entendemos ahora, pero ser&aacute; un actor importante dentro del mercado, del mismo modo que tambi&eacute;n suceder&aacute; con el coworking.&nbsp;<\/p>\n<p><strong>&iquest;Se ha recurrido la nueva ley del alquiler de la Generalitat? &iquest;Creen que es inconstitucional? En caso afirmativo &iquest;qu&eacute; plazos habr&iacute;a para la anulaci&oacute;n de esta ley? <\/strong><\/p>\n<p>(L. Catal&agrave;) Recurrida por PP y Cs ante el TC. El Consell de Garant&iacute;es Estatut&agrave;ries ya adelant&oacute; en un dictamen no vinculante que la mayor&iacute;a del articulado era inconstitucional.<\/p>\n<p><strong>En cuanto a los nuevos contratos de alquiler, &iquest;Se puede separar el parking si tiene dos referencias catastrales? &iquest;Entonces el parking se deber&iacute;a hacer contrato con IVA?&nbsp;<\/strong><br \/>\n(L. Catal&agrave;) Perfectamente. Nadie est&aacute; obligado a arrendar en un mismo contrato vivienda y parking. En el supuesto de contratos distintos el arrendamiento del parking devenga IVA.<\/p>\n<p><strong>&iquest;Qu&eacute; opina del hecho de que no se pueda solicitar en Catalunya una garant&iacute;a adicional o aval bancario en caso de que los ingresos del nuevo inquilino&nbsp; sean&nbsp; insuficientes para dar una tranquilidad de solvencia al propietario?<\/strong><\/p>\n<p>(G. Bernardos) Me parece francamente mal. La legislaci&oacute;n es cada vez menos equilibrada y en lugar de tener una equidistancia entre los derechos de los inquilinos y los propietarios, cada vez &eacute;sta tira m&aacute;s a favor del inquilino. Una situaci&oacute;n que puede hacer que muchos propietarios dejen de alquilar y decidan vender la vivienda con los efectos contraproducentes sobre el mercado de alquiler. Me parecer&iacute;a que esta medida que usted indica es muy adecuada por la sencilla raz&oacute;n de que el inquilino debe intentar garantizarse la solvencia sin incurrir en costes adicionales que le hagan contratar un seguro de alquiler.<\/p>\n<p><strong>&iquest;Qu&eacute; previsi&oacute;n hay sobre la restricci&oacute;n bancaria de dar cr&eacute;ditos\/hipotecas para la compra de vivienda?<\/strong><\/p>\n<p>(G. Bernardos) En la actualidad, para los clientes solventes, ni mucho menos hoy en d&iacute;a hay los mismos solventes que hace 10 meses. No creo que haya ninguna restricci&oacute;n. Las entidades compiten con bastante nobleza entre ellas para lograr el m&aacute;ximo de clientes posibles y les ofrecen unas condiciones espectaculares, en bastantes casos, si uno sabe negociar bien, entre el 1% y el 1,5% de inter&eacute;s. Las agencias inmobiliarias y los promotores, durante bastante tiempo han tenido miedo de que sucediera como en la crisis anterior y se les empezaran a caer operaciones pactadas por la falta de cr&eacute;dito bancario. No est&aacute; sucediendo as&iacute;. Los agentes y promotores consultados pr&aacute;cticamente ninguno me dice que se le ha ca&iacute;do ninguna operaci&oacute;n por este motivo. No obstante no ser&iacute;a de extra&ntilde;ar que los criterios se endurecieran si la crisis se alarga y vuelve otro confinamiento.<\/p>\n<p><strong>&iquest;Qu&eacute; previsi&oacute;n hay sobre la restricci&oacute;n bancaria de dar cr&eacute;ditos\/hipotecas para la compra de oficinas y locales comerciales?<\/strong><\/p>\n<p>(G. Bernardos) La previsi&oacute;n es que el barco se comporte de una manera bastante m&aacute;s estricta que con la vivienda. Que el tipo de inter&eacute;s sea superior y el importe prestado bastante inferior. Dudo mucho que la inmensa mayor&iacute;a den m&aacute;s del 50% de la tasaci&oacute;n de la oficina-local comercial en forma de hipoteca. El tema es que cuando vienen mal dadas, los locales comerciales y las oficinas tienen m&aacute;s la perspectiva de caer m&aacute;s su precio que el precio de la vivienda. Y por lo tanto, la garant&iacute;a no es tan buena. Adem&aacute;s, las oficinas y los locales comerciales presentan un mayor riesgo de desocupaci&oacute;n que la vivienda y por lo tanto m&aacute;s dificultad para que el propietario pueda sufragar las correspondientes cuotas hipotecarias. No obstante, en materia inmobiliaria, las entidades financieras no se han echado para atr&aacute;s en la concesi&oacute;n de cr&eacute;ditos como sucedi&oacute; en la d&eacute;cada pasada. Es posible que esto pueda llegar a suceder si la situaci&oacute;n econ&oacute;mica empeora y el confinamiento vuelva aunque solo sea unas semanas.<\/p>\n<p><strong>Miedo da que la bajada de precios en el &aacute;rea metropolitana nos deje a la 3&ordf; o 4 Corona con pol&iacute;gonos industriales desiertos. &iquest;Qu&eacute; estrategia se puede plantear para que no pase?<\/strong><\/p>\n<p>(G. Bernardos) La &uacute;nica estrategia que se puede plantear para que esto no pase es la conversi&oacute;n de diversas naves industriales en naves log&iacute;sticas. No obstante esto tiene un coste importante, unas necesidades de espacio que pr&aacute;cticamente esa posibilidad la hacen en la inmensa mayor&iacute;a de los casos que sea descartable. La crisis es una crisis&nbsp; b&aacute;sicamente en materia de servicios, menos en materia industrial, pero no le niego que existen muchas posibilidades de que propietarios que tengan vacantes naves industriales porque se les ha marchado el inquilino puedan recurrir a hacer ofertas muy jugosas a inquilinos que est&aacute;n en la 3&ordf; o 4&ordf; Corona con la posibilidad de que pagando pr&aacute;cticamente la misma renta tengan una ubicaci&oacute;n mejor. Esto es lo que generalmente sucede cuando las cosas van mal en los mercados de naves industriales y por ello es una posibilidad que usted solo puede combatir haci&eacute;ndole a ese inquilino de la nave industrial una oferta que signifique una bajada de precio y que haga que su nave vuelva a ser competitiva. No obstante le recomendar&iacute;a que no hiciera esto hasta que se cercione de que ese inquilino tenga una oferta en firme para irse a una nave mejor. No es como la d&eacute;cada pasada. La crisis no afecta tanto a la industria y, en segundo lugar, esperamos que una vez la Covid-19 haya desaparecido por la vacuna la econom&iacute;a se reactive.&nbsp;<\/p>\n<p><strong>La inversi&oacute;n alternativa busca ahora mismo una mayor rentabilidad debido al riesgo justamente sobre proyectos que ven su viabilidad disminuida. &iquest;Alguna propuesta para quebrar este c&iacute;rculo vicioso?<\/strong><\/p>\n<p>(G. Bernardos) No hay propuesta porque no hay posibilidad de romperlo hasta que la situaci&oacute;n econ&oacute;mica mejore. Cuando la situaci&oacute;n econ&oacute;mica mejore nos vamos a encontrar el que el riesgo va a bajar y la rentabilidad va a subir. Pero en ese momento, aquellos que se plantean invertir plantean que cualquier inversi&oacute;n tiene un riesgo mayor que en el pasado. Por lo tanto ya sabe usted la relaci&oacute;n directa &ldquo;m&aacute;s resigo, m&aacute;s rentabilidad&rdquo;. No obstante esa rentabilidad es muy dif&iacute;cil encontrarla a trav&eacute;s del alquiler porque el alquiler de todos los activos comerciales est&aacute; bajando su precio excepto, quiz&aacute;s, el de naves log&iacute;sticas, que si lo hace lo hace en una peque&ntilde;a cuant&iacute;a y por lo tanto la &uacute;nica posibilidad de que el inversor se vea compensado es comprar muy barato, para luego, cuando la econom&iacute;a se recupere pueda vender con un precio mucho mayor al adquirido y conseguir una plusval&iacute;a que le compense el riesgo. Es indiscutiblemente lo que ocurre sobre todo en las grandes crisis y por lo tanto la &uacute;nica posibilidad es alguien que no compre para alquilar sino que compre con la finalidad especulativa pensando que una r&aacute;pida recuperaci&oacute;n de la econom&iacute;a enseguida provoca una importante subida de precios. Un aspecto que est&aacute; por ver porque deber&iacute;amos esperar a ver la intensidad de la recuperaci&oacute;n en el 2021-2022. Para m&iacute;, la recuperaci&oacute;n econ&oacute;mica ser&aacute; muy intensa pero tengo mis dudas de que haya un traslado r&aacute;pido al inmobiliario porque siempre el inmobiliario, tanto para las bajadas de precio como para las subidas va por detr&aacute;s de la econom&iacute;a.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FORCADELL ha presentat en format webinar l&rsquo;edici&oacute; 2020 de l&rsquo;informe ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI elaborat conjuntament amb la Universitat de Barcelona. La pon&egrave;ncia principal ha estat a c&agrave;rrec del Director Editorial de l&rsquo;Informe FORCADELL-UB, el dr. Gonzalo Bernardos, professor titular d&rsquo;Economia de la UB i Director del M&agrave;ster d&rsquo;Assessoria, Gesti&oacute; i Promoci&oacute; Immobili&agrave;ria [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":21946,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[69,75],"tags":[],"class_list":["post-19499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-de-mercado","category-actualitat-de-mercat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FORCADELL i la UB han presentat l\u2019INFORME ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI 2020 - Forcadell<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FORCADELL i la UB han presentat l\u2019INFORME ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI 2020 - Forcadell\" \/>\n<meta property=\"og:description\" content=\"FORCADELL ha presentat en format webinar l&rsquo;edici&oacute; 2020 de l&rsquo;informe ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI elaborat conjuntament amb la Universitat de Barcelona. La pon&egrave;ncia principal ha estat a c&agrave;rrec del Director Editorial de l&rsquo;Informe FORCADELL-UB, el dr. Gonzalo Bernardos, professor titular d&rsquo;Economia de la UB i Director del M&agrave;ster d&rsquo;Assessoria, Gesti&oacute; i Promoci&oacute; Immobili&agrave;ria [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Forcadell\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-26T15:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T15:12:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forcadell.com\/wp-content\/uploads\/2020\/10\/forcadell-y-la-ub-han-presentado-el-informe-actualidad-y-perspectivas-del-sector-inmobiliario-2020.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2667\" \/>\n\t<meta property=\"og:image:height\" content=\"1751\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Joan S\u00e1nchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joan S\u00e1nchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuts\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FORCADELL i la UB han presentat l\u2019INFORME ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI 2020 - Forcadell","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/","og_locale":"ca_ES","og_type":"article","og_title":"FORCADELL i la UB han presentat l\u2019INFORME ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI 2020 - Forcadell","og_description":"FORCADELL ha presentat en format webinar l&rsquo;edici&oacute; 2020 de l&rsquo;informe ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI elaborat conjuntament amb la Universitat de Barcelona. La pon&egrave;ncia principal ha estat a c&agrave;rrec del Director Editorial de l&rsquo;Informe FORCADELL-UB, el dr. Gonzalo Bernardos, professor titular d&rsquo;Economia de la UB i Director del M&agrave;ster d&rsquo;Assessoria, Gesti&oacute; i Promoci&oacute; Immobili&agrave;ria [&hellip;]","og_url":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/","og_site_name":"Forcadell","article_published_time":"2020-10-26T15:03:00+00:00","article_modified_time":"2024-10-02T15:12:11+00:00","og_image":[{"width":2667,"height":1751,"url":"https:\/\/forcadell.com\/wp-content\/uploads\/2020\/10\/forcadell-y-la-ub-han-presentado-el-informe-actualidad-y-perspectivas-del-sector-inmobiliario-2020.png","type":"image\/png"}],"author":"Joan S\u00e1nchez","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Joan S\u00e1nchez","Temps estimat de lectura":"15 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/#article","isPartOf":{"@id":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/"},"author":{"name":"Joan S\u00e1nchez","@id":"https:\/\/forcadell.com\/ca\/#\/schema\/person\/1a2ac27005fa1cd1468319ce331748fb"},"headline":"FORCADELL i la UB han presentat l\u2019INFORME ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI 2020","datePublished":"2020-10-26T15:03:00+00:00","dateModified":"2024-10-02T15:12:11+00:00","mainEntityOfPage":{"@id":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/"},"wordCount":3801,"image":{"@id":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/forcadell.com\/wp-content\/uploads\/2020\/10\/forcadell-y-la-ub-han-presentado-el-informe-actualidad-y-perspectivas-del-sector-inmobiliario-2020.png","articleSection":["Actualidad de mercado","Actualitat de mercat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/","url":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/","name":"FORCADELL i la UB han presentat l\u2019INFORME ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI 2020 - Forcadell","isPartOf":{"@id":"https:\/\/forcadell.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/#primaryimage"},"image":{"@id":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/forcadell.com\/wp-content\/uploads\/2020\/10\/forcadell-y-la-ub-han-presentado-el-informe-actualidad-y-perspectivas-del-sector-inmobiliario-2020.png","datePublished":"2020-10-26T15:03:00+00:00","dateModified":"2024-10-02T15:12:11+00:00","author":{"@id":"https:\/\/forcadell.com\/ca\/#\/schema\/person\/1a2ac27005fa1cd1468319ce331748fb"},"breadcrumb":{"@id":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/#primaryimage","url":"https:\/\/forcadell.com\/wp-content\/uploads\/2020\/10\/forcadell-y-la-ub-han-presentado-el-informe-actualidad-y-perspectivas-del-sector-inmobiliario-2020.png","contentUrl":"https:\/\/forcadell.com\/wp-content\/uploads\/2020\/10\/forcadell-y-la-ub-han-presentado-el-informe-actualidad-y-perspectivas-del-sector-inmobiliario-2020.png","width":2667,"height":1751},{"@type":"BreadcrumbList","@id":"https:\/\/forcadell.com\/ca\/forcadell-i-la-ub-han-presentat-linforme-actualitat-i-perspectives-del-sector-immobiliari-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/forcadell.com\/ca\/"},{"@type":"ListItem","position":2,"name":"FORCADELL i la UB han presentat l\u2019INFORME ACTUALITAT I PERSPECTIVES DEL SECTOR IMMOBILIARI 2020"}]},{"@type":"WebSite","@id":"https:\/\/forcadell.com\/ca\/#website","url":"https:\/\/forcadell.com\/ca\/","name":"Forcadell","description":"Inmobiliaria Barcelona | Consultores inmobiliarios","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forcadell.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/forcadell.com\/ca\/#\/schema\/person\/1a2ac27005fa1cd1468319ce331748fb","name":"Joan S\u00e1nchez","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/4ae12daa48f67eb46a5a8d3863a05fa2cb6ba8990aabfbb6a76a64cb138937a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ae12daa48f67eb46a5a8d3863a05fa2cb6ba8990aabfbb6a76a64cb138937a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ae12daa48f67eb46a5a8d3863a05fa2cb6ba8990aabfbb6a76a64cb138937a9?s=96&d=mm&r=g","caption":"Joan S\u00e1nchez"}}]}},"_links":{"self":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts\/19499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/comments?post=19499"}],"version-history":[{"count":1,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts\/19499\/revisions"}],"predecessor-version":[{"id":19968,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/posts\/19499\/revisions\/19968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/media\/21946"}],"wp:attachment":[{"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/media?parent=19499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/categories?post=19499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/forcadell.com\/ca\/wp-json\/wp\/v2\/tags?post=19499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}